{"id":12,"count":28,"description":"","link":"http:\/\/www.salinasdeoro.es\/eu\/category\/portal-de-transparencia-2\/","name":"Portal de Transparencia","slug":"portal-de-transparencia-2","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Portal de Transparencia archivos - Jaitzeko Udala<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"http:\/\/www.salinasdeoro.es\/eu\/category\/portal-de-transparencia-2\/\" \/>\r\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Portal de Transparencia archivos - Jaitzeko Udala\" \/>\r\n<meta property=\"og:url\" content=\"http:\/\/www.salinasdeoro.es\/eu\/category\/portal-de-transparencia-2\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Jaitzeko Udala\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\/\/www.salinasdeoro.es\/eu\/category\/portal-de-transparencia-2\/\",\"url\":\"http:\/\/www.salinasdeoro.es\/eu\/category\/portal-de-transparencia-2\/\",\"name\":\"Portal de Transparencia archivos - Jaitzeko Udala\",\"isPartOf\":{\"@id\":\"http:\/\/www.salinasdeoro.es\/eu\/#website\"},\"breadcrumb\":{\"@id\":\"http:\/\/www.salinasdeoro.es\/eu\/category\/portal-de-transparencia-2\/#breadcrumb\"},\"inLanguage\":\"eu-ES\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.salinasdeoro.es\/eu\/category\/portal-de-transparencia-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/www.salinasdeoro.es\/eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portal de Transparencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.salinasdeoro.es\/eu\/#website\",\"url\":\"http:\/\/www.salinasdeoro.es\/eu\/\",\"name\":\"Jaitzeko Udala\",\"description\":\"Jaitzeko Udala\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.salinasdeoro.es\/eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Portal de Transparencia archivos - Jaitzeko Udala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.salinasdeoro.es\/eu\/category\/portal-de-transparencia-2\/","og_locale":"eu_ES","og_type":"article","og_title":"Portal de Transparencia archivos - Jaitzeko Udala","og_url":"http:\/\/www.salinasdeoro.es\/eu\/category\/portal-de-transparencia-2\/","og_site_name":"Jaitzeko Udala","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/www.salinasdeoro.es\/eu\/category\/portal-de-transparencia-2\/","url":"http:\/\/www.salinasdeoro.es\/eu\/category\/portal-de-transparencia-2\/","name":"Portal de Transparencia archivos - Jaitzeko Udala","isPartOf":{"@id":"http:\/\/www.salinasdeoro.es\/eu\/#website"},"breadcrumb":{"@id":"http:\/\/www.salinasdeoro.es\/eu\/category\/portal-de-transparencia-2\/#breadcrumb"},"inLanguage":"eu-ES"},{"@type":"BreadcrumbList","@id":"http:\/\/www.salinasdeoro.es\/eu\/category\/portal-de-transparencia-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/www.salinasdeoro.es\/eu\/"},{"@type":"ListItem","position":2,"name":"Portal de Transparencia"}]},{"@type":"WebSite","@id":"http:\/\/www.salinasdeoro.es\/eu\/#website","url":"http:\/\/www.salinasdeoro.es\/eu\/","name":"Jaitzeko Udala","description":"Jaitzeko Udala","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.salinasdeoro.es\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"}]}},"_links":{"self":[{"href":"http:\/\/www.salinasdeoro.es\/eu\/wp-json\/wp\/v2\/categories\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.salinasdeoro.es\/eu\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/www.salinasdeoro.es\/eu\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/www.salinasdeoro.es\/eu\/wp-json\/wp\/v2\/posts?categories=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}